{"id":7365,"date":"2025-01-02T05:43:22","date_gmt":"2025-01-02T05:43:22","guid":{"rendered":"https:\/\/www.mokiecig.com\/?post_type=product&#038;p=7365"},"modified":"2025-01-02T05:44:54","modified_gmt":"2025-01-02T05:44:54","slug":"m67-cool-mint-vape-box","status":"publish","type":"product","link":"https:\/\/www.mokivape.com\/es\/producto\/m67-caja-de-menta-fresca\/","title":{"rendered":"M67 Cool Mint Vape Box"},"content":{"rendered":"<div data-elementor-type=\"product-post\" data-elementor-id=\"7365\" class=\"elementor elementor-7365\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60b77a72 e-flex e-con-boxed e-con e-parent\" data-id=\"60b77a72\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c7f30c elementor-widget elementor-widget-heading\" data-id=\"5c7f30c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M67 Cool Mint Vape Box<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e070226 elementor-widget elementor-widget-text-editor\" data-id=\"e070226\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMOKI Dual Mesh Coil Cool Mint Vape MK-M67 ofrece una experiencia de vapeo mejorada con la serie Open Pod. Estos kits cuentan con una bobina de malla doble para un calentamiento uniforme y sabor intenso. MOKI ofrece marca blanca vape bar y vape etiqueta privada para su marca vaping, MK-M67 es perfecto para la marca personalizada.\r\nComo un producto de alta calidad, venta caliente vaping, MK-M67 apoyo hecho a la medida, que atienden a las necesidades del OEM y ODM. Como fabricante y proveedor de confianza, MOKI ofrece a sus socios el dise\u00f1o del logotipo y del paquete sin coste alguno.\r\nEste MOKI Dual Mesh Coil Cool Mint Vape Bar MK-M67 no es s\u00f3lo una opci\u00f3n vaping; es una opci\u00f3n de primera calidad para aquellos que buscan un sistema de vaina abierta superior.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc3e0f elementor-widget elementor-widget-html\" data-id=\"6dc3e0f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tg-wrap\"><table><tbody><tr><td>Talla<\/td><td>46*23.45*103mm<\/td><td>Puerto de carga<\/td><td>Tipo-C<\/td><\/tr><tr><td>Material<\/td><td>PC<\/td><td>N\u00facleo atomizador<\/td><td>Bobina de doble malla<\/td><\/tr><tr><td>L\u00edquido electr\u00f3nico<\/td><td>13 ml<\/td><td>Capacidad de la bater\u00eda<\/td><td>680 mAh<\/td><\/tr><tr><td>Rango de resistencia<\/td><td>0.65\u03a9<\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab03d27 elementor-widget elementor-widget-image\" data-id=\"ab03d27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_01.jpg\" class=\"attachment-large size-large wp-image-7928\" alt=\"M67 caja de menta fresca\" srcset=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_01.jpg 800w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_01-768x432.jpg 768w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_01-18x10.jpg 18w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_01-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-133fae3 elementor-widget elementor-widget-image\" data-id=\"133fae3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"451\" src=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_02.jpg\" class=\"attachment-large size-large wp-image-7929\" alt=\"M67 menta fresca vape caja LED pantalla de luz\" srcset=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_02.jpg 800w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_02-768x433.jpg 768w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_02-18x10.jpg 18w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_02-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf5de1b elementor-widget elementor-widget-image\" data-id=\"bf5de1b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"449\" src=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_03.jpg\" class=\"attachment-large size-large wp-image-7930\" alt=\"especificaciones de M67 cool mint vape box\" srcset=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_03.jpg 800w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_03-768x431.jpg 768w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_03-18x10.jpg 18w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_03-600x337.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2e0d9d elementor-widget elementor-widget-image\" data-id=\"e2e0d9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_04-1.jpg\" class=\"attachment-large size-large wp-image-7931\" alt=\"estructura de M67 cool mint vape box 5-star vape kits\" srcset=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_04-1.jpg 800w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_04-1-768x432.jpg 768w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_04-1-18x10.jpg 18w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_04-1-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf290c elementor-widget elementor-widget-image\" data-id=\"5bf290c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_05.jpg\" class=\"attachment-large size-large wp-image-7932\" alt=\"M67 cool mint vape box recargable\" srcset=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_05.jpg 800w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_05-768x432.jpg 768w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_05-18x10.jpg 18w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_05-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-047d701 elementor-widget elementor-widget-image\" data-id=\"047d701\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_06.jpg\" class=\"attachment-large size-large wp-image-7933\" alt=\"colores de la caja de menta fresca M67\" srcset=\"https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_06.jpg 800w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_06-768x432.jpg 768w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_06-18x10.jpg 18w, https:\/\/www.mokivape.com\/wp-content\/uploads\/2025\/01\/MK_M67_cool_mint_vape_bar_06-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>MOKI Dual Mesh Coil Cool Mint Vape MK-M67 ofrece una experiencia de vapeo mejorada con la serie Open Pod. Estos kits cuentan con una bobina de malla doble para un calentamiento uniforme y sabor intenso. MOKI ofrece marca blanca vape bar y vape etiqueta privada para su marca vaping, MK-M67 es perfecto para la marca personalizada.<br \/>\nComo producto de vapeo de alta calidad y gran demanda, MK-M67 se fabrica bajo pedido y satisface las necesidades de OEM y ODM. Como fabricante y proveedor de confianza, MOKI ofrece a sus socios el dise\u00f1o del logotipo y del envase sin coste alguno.<br \/>\nEste MOKI Dual Mesh Coil Cool Mint Vape Bar MK-M67 no es s\u00f3lo una opci\u00f3n vaping; es una opci\u00f3n de primera calidad para aquellos que buscan un sistema de vaina abierta superior.<\/p>","protected":false},"featured_media":7927,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[31,16],"product_tag":[],"class_list":{"0":"post-7365","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-disposable-vape-pod-kits-oem-vape-pen-manufacturing","7":"product_cat-pod-kits-refillable-open-pods-cartridge-oem","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/product\/7365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/comments?post=7365"}],"version-history":[{"count":0,"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/product\/7365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/media\/7927"}],"wp:attachment":[{"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/media?parent=7365"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/product_brand?post=7365"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/product_cat?post=7365"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mokivape.com\/es\/wp-json\/wp\/v2\/product_tag?post=7365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}